{"id":10428,"date":"2024-10-05T15:48:41","date_gmt":"2024-10-05T13:48:41","guid":{"rendered":"https:\/\/sapor.pl\/non-categorizzato\/norme-applicabili-e-denominazioni-delle-finestre\/"},"modified":"2025-01-11T05:09:23","modified_gmt":"2025-01-11T04:09:23","slug":"norme-applicabili-e-denominazioni-delle-finestre","status":"publish","type":"post","link":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/","title":{"rendered":"Norme applicabili e denominazioni delle finestre"},"content":{"rendered":"<p>Oggi che si presta sempre pi\u00f9 attenzione all&#8217;efficienza energetica, al comfort acustico e alla sicurezza delle nostre case, vale la pena prestare attenzione alle norme e alle etichette applicabili alle finestre. Saperlo ci permetter\u00e0 di fare una scelta consapevole che contribuir\u00e0 al risparmio energetico e a migliorare la qualit\u00e0 della vita nei nostri quattro angoli di casa. Nel seguente articolo ti presentiamo le informazioni pi\u00f9 importanti sulle norme vigenti e sulle etichette delle finestre. <!--more--><\/p>\n<h2><\/h2>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-10407\" src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1.jpg\" data-orig-src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1.jpg\" alt=\"\" width=\"2048\" height=\"1150\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272048%27%20height%3D%271150%27%20viewBox%3D%270%200%202048%201150%27%3E%3Crect%20width%3D%272048%27%20height%3D%271150%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-200x112.jpg 200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-300x168.jpg 300w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-400x225.jpg 400w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-600x337.jpg 600w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-768x431.jpg 768w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-800x449.jpg 800w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-1024x575.jpg 1024w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-1200x674.jpg 1200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1-1536x863.jpg 1536w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1.jpg 2048w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<h2>Standard europei per le finestre<\/h2>\n<p>Le norme europee (EN) sono un insieme di regole e linee guida sviluppate dal Comitato Europeo di Normazione (CEN) per unificare i requisiti tecnici di vari prodotti, tra cui le finestre. Sono applicabili in tutti i paesi dell&#8217;Unione Europea, compresa la Polonia. Nel caso delle finestre, le norme pi\u00f9 importanti sono la <strong>EN 14351 e la EN 1627<\/strong>. La prima riguarda i requisiti generali delle finestre e delle porte esterne, come la tenuta all&#8217;aria, la resistenza all&#8217;acqua o la resistenza ai carichi meccanici. La seconda specifica i requisiti per la protezione antieffrazione.<\/p>\n<h2><img decoding=\"async\" class=\"lazyload size-full wp-image-10400 aligncenter\" src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien.jpg\" data-orig-src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien.jpg\" alt=\"\" width=\"2048\" height=\"1150\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272048%27%20height%3D%271150%27%20viewBox%3D%270%200%202048%201150%27%3E%3Crect%20width%3D%272048%27%20height%3D%271150%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-200x112.jpg 200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-300x168.jpg 300w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-400x225.jpg 400w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-600x337.jpg 600w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-768x431.jpg 768w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-800x449.jpg 800w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-1024x575.jpg 1024w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-1200x674.jpg 1200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-1536x863.jpg 1536w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien.jpg 2048w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/h2>\n<h2>Oznaczenia energetyczne okien<\/h2>\n<p>L&#8217;etichettatura energetica delle finestre ci informa sull&#8217;efficienza energetica di un prodotto, che consente di <strong>risparmiare energia e ridurre le emissioni di CO2<\/strong>. Per le finestre, i parametri pi\u00f9 importanti sono il coefficiente di trasferimento del calore (Uw) e il fattore solare (g). Pi\u00f9 basso \u00e8 il fattore Uw, migliore \u00e8 l&#8217;<strong>isolamento termico della finestra<\/strong>, mentre un fattore g pi\u00f9 alto significa maggiori benefici per l&#8217;energia solare. In Polonia esiste un sistema di etichettatura energetica che va da A++ a E, dove A+++ indica la migliore efficienza energetica. <img decoding=\"async\" class=\"lazyload size-full wp-image-10382 aligncenter\" src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2.jpg\" data-orig-src=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2.jpg\" alt=\"\" width=\"2048\" height=\"1150\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272048%27%20height%3D%271150%27%20viewBox%3D%270%200%202048%201150%27%3E%3Crect%20width%3D%272048%27%20height%3D%271150%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-200x112.jpg 200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-300x168.jpg 300w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-400x225.jpg 400w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-600x337.jpg 600w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-768x431.jpg 768w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-800x449.jpg 800w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1024x575.jpg 1024w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1200x674.jpg 1200w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2-1536x863.jpg 1536w, https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/Obowiazujace-normy-i-oznaczenia-okien-2.jpg 2048w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<h2>Certificati di qualit\u00e0 e sicurezza<\/h2>\n<p>Quando si scelgono le finestre, \u00e8 bene prestare attenzione anche ai certificati di qualit\u00e0 e sicurezza di cui sono dotate. In Polonia, i certificati pi\u00f9 conosciuti sono il marchio CE e il certificato ITB. Il marchio CE significa che un determinato prodotto soddisfa i requisiti delle direttive europee e che <a href=\"https:\/\/sapor.pl\/\">il produttore di finestre in plastica<\/a>, e non solo, dichiara la conformit\u00e0 agli standard applicabili. Il certificato ITB, invece, viene rilasciato dal Building Research Institute e conferma la conformit\u00e0 del prodotto agli standard polacchi e la sua alta qualit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi che si presta sempre pi\u00f9 attenzione all&#8217;efficienza energetica, al  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":10368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[370],"tags":[],"class_list":["post-10428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni<\/title>\n<meta name=\"description\" content=\"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l&#039;efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni\" \/>\n<meta property=\"og:description\" content=\"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l&#039;efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sapor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-05T13:48:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-11T04:09:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wenet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"wenet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/\"},\"author\":{\"name\":\"wenet\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/person\\\/81e7f7a73c94a4b161f4c4ff67c1f089\"},\"headline\":\"Norme applicabili e denominazioni delle finestre\",\"datePublished\":\"2024-10-05T13:48:41+00:00\",\"dateModified\":\"2025-01-11T04:09:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NORME-EUROPEE.jpg\",\"articleSection\":[\"TUTTI\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/\",\"url\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/\",\"name\":\"Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NORME-EUROPEE.jpg\",\"datePublished\":\"2024-10-05T13:48:41+00:00\",\"dateModified\":\"2025-01-11T04:09:23+00:00\",\"description\":\"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l'efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NORME-EUROPEE.jpg\",\"contentUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NORME-EUROPEE.jpg\",\"width\":2048,\"height\":1150,\"caption\":\"NORME EUROPEE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/it\\\/tutti\\\/norme-applicabili-e-denominazioni-delle-finestre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/sapor.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Norme applicabili e denominazioni delle finestre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sapor.pl\\\/en\\\/\",\"name\":\"Sapor\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\",\"name\":\"Sapor Sp. z o. o.\",\"url\":\"https:\\\/\\\/sapor.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-sapor-e1618419520128.png\",\"contentUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-sapor-e1618419520128.png\",\"width\":140,\"height\":67,\"caption\":\"Sapor Sp. z o. o.\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAPOR.Fabryka.okien.i.drzwi\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/person\\\/81e7f7a73c94a4b161f4c4ff67c1f089\",\"name\":\"wenet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g\",\"caption\":\"wenet\"},\"url\":\"https:\\\/\\\/sapor.pl\\\/it\\\/author\\\/wenet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni","description":"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l'efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/","og_locale":"it_IT","og_type":"article","og_title":"Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni","og_description":"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l'efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.","og_url":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/","og_site_name":"Sapor","article_publisher":"https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/","article_published_time":"2024-10-05T13:48:41+00:00","article_modified_time":"2025-01-11T04:09:23+00:00","og_image":[{"width":2048,"height":1150,"url":"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg","type":"image\/jpeg"}],"author":"wenet","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"wenet","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#article","isPartOf":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/"},"author":{"name":"wenet","@id":"https:\/\/sapor.pl\/en\/#\/schema\/person\/81e7f7a73c94a4b161f4c4ff67c1f089"},"headline":"Norme applicabili e denominazioni delle finestre","datePublished":"2024-10-05T13:48:41+00:00","dateModified":"2025-01-11T04:09:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/"},"wordCount":356,"publisher":{"@id":"https:\/\/sapor.pl\/en\/#organization"},"image":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#primaryimage"},"thumbnailUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg","articleSection":["TUTTI"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/","url":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/","name":"Quali sono gli standard e le marcature che si applicano alle finestre? Controlla le informazioni","isPartOf":{"@id":"https:\/\/sapor.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#primaryimage"},"image":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#primaryimage"},"thumbnailUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg","datePublished":"2024-10-05T13:48:41+00:00","dateModified":"2025-01-11T04:09:23+00:00","description":"Conoscere gli standard e le etichette delle finestre \u00e8 fondamentale per la sicurezza e l'efficienza energetica della tua casa. Scopri di pi\u00f9 e fai una scelta consapevole.","breadcrumb":{"@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#primaryimage","url":"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg","contentUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2024\/08\/NORME-EUROPEE.jpg","width":2048,"height":1150,"caption":"NORME EUROPEE"},{"@type":"BreadcrumbList","@id":"https:\/\/sapor.pl\/it\/tutti\/norme-applicabili-e-denominazioni-delle-finestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/sapor.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Norme applicabili e denominazioni delle finestre"}]},{"@type":"WebSite","@id":"https:\/\/sapor.pl\/en\/#website","url":"https:\/\/sapor.pl\/en\/","name":"Sapor","description":"","publisher":{"@id":"https:\/\/sapor.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sapor.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sapor.pl\/en\/#organization","name":"Sapor Sp. z o. o.","url":"https:\/\/sapor.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sapor.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sapor.pl\/wp-content\/uploads\/2021\/04\/logo-sapor-e1618419520128.png","contentUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2021\/04\/logo-sapor-e1618419520128.png","width":140,"height":67,"caption":"Sapor Sp. z o. o."},"image":{"@id":"https:\/\/sapor.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/"]},{"@type":"Person","@id":"https:\/\/sapor.pl\/en\/#\/schema\/person\/81e7f7a73c94a4b161f4c4ff67c1f089","name":"wenet","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba90f968bb31cbecf6444ed388f8c5bd5d9803a1e56d3674bd89c22985e049d?s=96&d=mm&r=g","caption":"wenet"},"url":"https:\/\/sapor.pl\/it\/author\/wenet\/"}]}},"_links":{"self":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts\/10428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/comments?post=10428"}],"version-history":[{"count":2,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts\/10428\/revisions"}],"predecessor-version":[{"id":10438,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts\/10428\/revisions\/10438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/media\/10368"}],"wp:attachment":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/media?parent=10428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/categories?post=10428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/tags?post=10428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}