{"id":10652,"date":"2024-11-11T11:09:02","date_gmt":"2024-11-11T10:09:02","guid":{"rendered":"https:\/\/sapor.pl\/?p=10652"},"modified":"2025-01-11T07:10:10","modified_gmt":"2025-01-11T06:10:10","slug":"recensione-del-sistema-aluprof-mb-79n","status":"publish","type":"post","link":"https:\/\/sapor.pl\/it\/tutti\/recensione-del-sistema-aluprof-mb-79n\/","title":{"rendered":"Recensione del Sistema Aluprof MB-79N"},"content":{"rendered":"<p class=\"whitespace-pre-wrap break-words\">Il sistema Aluprof MB-79N rivoluziona le soluzioni per finestre e porte raggiungendo un eccezionale coefficiente di trasmittanza termica di soli 0,83 W\/(m\u00b2K), permettendo alle finestre di raggiungere un impressionante valore Uw fino a 0,64 W\/(m\u00b2K).<\/p>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Varianti del Sistema<\/h2>\n<p class=\"whitespace-pre-wrap break-words\">Variante MB-79N E:<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Guarnizione centrale monocomponente<\/li>\n<li class=\"whitespace-normal break-words\">Soluzione economica<\/li>\n<li class=\"whitespace-normal break-words\">Ideale per applicazioni standard<\/li>\n<\/ul>\n<p class=\"whitespace-pre-wrap break-words\">Variante MB-79N ST:<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Guarnizione centrale bicomponente<\/li>\n<li class=\"whitespace-normal break-words\">Prestazioni termiche migliorate<\/li>\n<li class=\"whitespace-normal break-words\">Ideale per progetti che richiedono un maggiore isolamento termico<\/li>\n<\/ul>\n<p class=\"whitespace-pre-wrap break-words\">Variante MB-79N SI:<\/p>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Inserti isolanti in EPS con guarnizione bicomponente<\/li>\n<li class=\"whitespace-normal break-words\">Massima efficienza termica<\/li>\n<li class=\"whitespace-normal break-words\">Soluzione premium per i pi\u00f9 elevati requisiti termici<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Parametri Tecnici:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Isolamento Termico (Uf): &lt;0,83 W\/(m\u00b2K)<\/li>\n<li class=\"whitespace-normal break-words\">Tenuta all&#8217;Acqua: E1950<\/li>\n<li class=\"whitespace-normal break-words\">Permeabilit\u00e0 all&#8217;Aria: Classe 4<\/li>\n<li class=\"whitespace-normal break-words\">Dimensioni Massime Anta: H: 2700mm, L: 1400mm<\/li>\n<li class=\"whitespace-normal break-words\">Peso Massimo Anta: 200 kg<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Possibilit\u00e0 Costruttive:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Finestre fisse e porte balcone<\/li>\n<li class=\"whitespace-normal break-words\">Finestre con apertura verso l&#8217;interno e l&#8217;esterno<\/li>\n<li class=\"whitespace-normal break-words\">Montanti standard ed espansibili<\/li>\n<li class=\"whitespace-normal break-words\">Porte esterne ad una e due ante<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Parametri Massimi:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Altezza: 2,8 metri<\/li>\n<li class=\"whitespace-normal break-words\">Larghezza: 1,4 metri<\/li>\n<li class=\"whitespace-normal break-words\">Peso: 200 kg<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Propriet\u00e0 Isolanti:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Trasmittanza termica finestra (Uw) da 0,64 W\/(m\u00b2K)<\/li>\n<li class=\"whitespace-normal break-words\">Soddisfa i Requisiti Tecnici 2021 per:\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Finestre (0,9 W\/m\u00b2K)<\/li>\n<li class=\"whitespace-normal break-words\">Porte (1,3 W\/m\u00b2K)<\/li>\n<\/ul>\n<\/li>\n<li class=\"whitespace-normal break-words\">Possibilit\u00e0 di vetrocamera fino a 63mm<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Resistenza agli Agenti Atmosferici:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Permeabilit\u00e0 all&#8217;Aria: Classe 4<\/li>\n<li class=\"whitespace-normal break-words\">Tenuta all&#8217;Acqua: E1950<\/li>\n<li class=\"whitespace-normal break-words\">Resistenza al Carico del Vento: Classe C5<\/li>\n<li class=\"whitespace-normal break-words\">Certificato secondo gli standard ASTM e Florida Building Code<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Caratteristiche Principali:<\/h2>\n<ul class=\"[&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc space-y-1.5 pl-7\">\n<li class=\"whitespace-normal break-words\">Profondit\u00e0 profilo: 79mm per ante finestra, 70mm per telai e ante porta<\/li>\n<li class=\"whitespace-normal break-words\">Design avanzato del taglio termico con materiali innovativi<\/li>\n<li class=\"whitespace-normal break-words\">Compatibile con vari tipi di vetro, incluse opzioni acustiche e antieffrazione<\/li>\n<li class=\"whitespace-normal break-words\">Compensazione delle deformazioni del pavimento in calcestruzzo fino a \u00b125,6 mm nelle applicazioni a parete finestrata<\/li>\n<\/ul>\n<h2 class=\"text-xl font-bold text-text-200 mt-1 -mb-0.5\">Conclusioni:<\/h2>\n<p class=\"whitespace-pre-wrap break-words\">Il sistema Aluprof MB-79N rappresenta un significativo progresso nella tecnologia delle finestre e porte in alluminio, combinando prestazioni termiche superiori con vantaggi costruttivi pratici. Con il suo valore Uw che raggiunge 0,64 W\/(m\u00b2K), si colloca tra i migliori sistemi per efficienza termica. Le tre varianti del sistema offrono un&#8217;eccellente flessibilit\u00e0 per diverse esigenze progettuali, mantenendo lo stesso livello di prezzo del precedente modello MB-70HI. Il sistema ha dimostrato la sua affidabilit\u00e0 in applicazioni reali, inclusi progetti prestigiosi come lo sviluppo di 625 Fulton Street a Brooklyn, dimostrando la sua capacit\u00e0 in progetti architettonici complessi.<\/p>\n<p class=\"whitespace-pre-wrap break-words\">\n","protected":false},"excerpt":{"rendered":"<p>Il sistema Aluprof MB-79N rivoluziona le soluzioni per finestre e  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":10641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[370],"tags":[],"class_list":["post-10652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recensione del Sistema Aluprof MB-79N - Sapor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sapor.pl\/en\/?p=10651\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recensione del Sistema Aluprof MB-79N - Sapor\" \/>\n<meta property=\"og:description\" content=\"Il sistema Aluprof MB-79N rivoluziona le soluzioni per finestre e [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sapor.pl\/en\/?p=10651\" \/>\n<meta property=\"og:site_name\" content=\"Sapor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T10:09:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-11T06:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administartor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administartor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651\"},\"author\":{\"name\":\"Administartor\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/person\\\/fef15ee2dea405965937d6f409d02942\"},\"headline\":\"Recensione del Sistema Aluprof MB-79N\",\"datePublished\":\"2024-11-11T10:09:02+00:00\",\"dateModified\":\"2025-01-11T06:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651\"},\"wordCount\":360,\"publisher\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/REVISIONE-finestra-in-alluminio-mb079-n.jpg\",\"articleSection\":[\"TUTTI\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651\",\"url\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651\",\"name\":\"Recensione del Sistema Aluprof MB-79N - Sapor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/REVISIONE-finestra-in-alluminio-mb079-n.jpg\",\"datePublished\":\"2024-11-11T10:09:02+00:00\",\"dateModified\":\"2025-01-11T06:10:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#primaryimage\",\"url\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/REVISIONE-finestra-in-alluminio-mb079-n.jpg\",\"contentUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/REVISIONE-finestra-in-alluminio-mb079-n.jpg\",\"width\":2048,\"height\":1150,\"caption\":\"REVISIONE finestra in alluminio mb079-n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?p=10651#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/sapor.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recensione del Sistema Aluprof MB-79N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sapor.pl\\\/en\\\/\",\"name\":\"Sapor\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sapor.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#organization\",\"name\":\"Sapor Sp. z o. o.\",\"url\":\"https:\\\/\\\/sapor.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-sapor-e1618419520128.png\",\"contentUrl\":\"https:\\\/\\\/sapor.pl\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-sapor-e1618419520128.png\",\"width\":140,\"height\":67,\"caption\":\"Sapor Sp. z o. o.\"},\"image\":{\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SAPOR.Fabryka.okien.i.drzwi\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sapor.pl\\\/en\\\/#\\\/schema\\\/person\\\/fef15ee2dea405965937d6f409d02942\",\"name\":\"Administartor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g\",\"caption\":\"Administartor\"},\"sameAs\":[\"https:\\\/\\\/sapor.pl\"],\"url\":\"https:\\\/\\\/sapor.pl\\\/it\\\/author\\\/sapor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recensione del Sistema Aluprof MB-79N - Sapor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sapor.pl\/en\/?p=10651","og_locale":"it_IT","og_type":"article","og_title":"Recensione del Sistema Aluprof MB-79N - Sapor","og_description":"Il sistema Aluprof MB-79N rivoluziona le soluzioni per finestre e [...]","og_url":"https:\/\/sapor.pl\/en\/?p=10651","og_site_name":"Sapor","article_publisher":"https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/","article_published_time":"2024-11-11T10:09:02+00:00","article_modified_time":"2025-01-11T06:10:10+00:00","og_image":[{"width":2048,"height":1150,"url":"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg","type":"image\/jpeg"}],"author":"Administartor","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Administartor","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sapor.pl\/en\/?p=10651#article","isPartOf":{"@id":"https:\/\/sapor.pl\/en\/?p=10651"},"author":{"name":"Administartor","@id":"https:\/\/sapor.pl\/en\/#\/schema\/person\/fef15ee2dea405965937d6f409d02942"},"headline":"Recensione del Sistema Aluprof MB-79N","datePublished":"2024-11-11T10:09:02+00:00","dateModified":"2025-01-11T06:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/sapor.pl\/en\/?p=10651"},"wordCount":360,"publisher":{"@id":"https:\/\/sapor.pl\/en\/#organization"},"image":{"@id":"https:\/\/sapor.pl\/en\/?p=10651#primaryimage"},"thumbnailUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg","articleSection":["TUTTI"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sapor.pl\/en\/?p=10651","url":"https:\/\/sapor.pl\/en\/?p=10651","name":"Recensione del Sistema Aluprof MB-79N - Sapor","isPartOf":{"@id":"https:\/\/sapor.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sapor.pl\/en\/?p=10651#primaryimage"},"image":{"@id":"https:\/\/sapor.pl\/en\/?p=10651#primaryimage"},"thumbnailUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg","datePublished":"2024-11-11T10:09:02+00:00","dateModified":"2025-01-11T06:10:10+00:00","breadcrumb":{"@id":"https:\/\/sapor.pl\/en\/?p=10651#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sapor.pl\/en\/?p=10651"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sapor.pl\/en\/?p=10651#primaryimage","url":"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg","contentUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2025\/01\/REVISIONE-finestra-in-alluminio-mb079-n.jpg","width":2048,"height":1150,"caption":"REVISIONE finestra in alluminio mb079-n"},{"@type":"BreadcrumbList","@id":"https:\/\/sapor.pl\/en\/?p=10651#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/sapor.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Recensione del Sistema Aluprof MB-79N"}]},{"@type":"WebSite","@id":"https:\/\/sapor.pl\/en\/#website","url":"https:\/\/sapor.pl\/en\/","name":"Sapor","description":"","publisher":{"@id":"https:\/\/sapor.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sapor.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sapor.pl\/en\/#organization","name":"Sapor Sp. z o. o.","url":"https:\/\/sapor.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sapor.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sapor.pl\/wp-content\/uploads\/2021\/04\/logo-sapor-e1618419520128.png","contentUrl":"https:\/\/sapor.pl\/wp-content\/uploads\/2021\/04\/logo-sapor-e1618419520128.png","width":140,"height":67,"caption":"Sapor Sp. z o. o."},"image":{"@id":"https:\/\/sapor.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SAPOR.Fabryka.okien.i.drzwi\/"]},{"@type":"Person","@id":"https:\/\/sapor.pl\/en\/#\/schema\/person\/fef15ee2dea405965937d6f409d02942","name":"Administartor","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf431a23c1196d3ec37215e2ffa5da763abfa7faae38be6c34e334dd97f27d15?s=96&d=mm&r=g","caption":"Administartor"},"sameAs":["https:\/\/sapor.pl"],"url":"https:\/\/sapor.pl\/it\/author\/sapor\/"}]}},"_links":{"self":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts\/10652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/comments?post=10652"}],"version-history":[{"count":0,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/posts\/10652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/media\/10641"}],"wp:attachment":[{"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/media?parent=10652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/categories?post=10652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sapor.pl\/it\/wp-json\/wp\/v2\/tags?post=10652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}